{"id":106,"date":"2015-07-26T21:53:54","date_gmt":"2015-07-26T19:53:54","guid":{"rendered":"http:\/\/www.alfonsiana.eu\/biblioteca\/?page_id=106"},"modified":"2022-10-17T16:46:01","modified_gmt":"2022-10-17T14:46:01","slug":"chi-siamo-3","status":"publish","type":"page","link":"https:\/\/www.alfonsiana.eu\/biblioteca\/chi-siamo-3\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"<p style=\"text-align: justify;\">Fin dalla fondazione della Casa Generalizia dei Padri Redentoristi nel 1855 esisteva una Biblioteca. Uno dei suoi primi fondi fu costituito dall&#8217;eredit\u00e0 delle collezioni appartenute al Cardinale Cl\u00e9ment de Villecourt (+ 17.1.1867). La direzione dei futuri sviluppi fu impressa dal P. Fran\u00e7ois Xavier Reuss (1842-1924), alsaziano, poeta latino, poliglotta, colto e di grande fama. Nel 1868 fu nominato bibliotecario e venne confermato per diversi decenni. Il Superiore Generale P. Nicolas Mauron (1818-1893) gli aveva affidato l&#8217;incarico di acquistare tutti i libri citati da S. Alfonso nelle sue opere morali, dogmatiche e ascetiche per la preparazione di un&#8217;edizione critica, soprattutto della &#8220;Theologia moralis&#8221; ed egli si dedic\u00f2 a questo compito \u201ccon uno zelo ed una perseveranza incredibili\u201d, sfruttando una situazione favorevole: la soppressione di molti conventi in Italia dopo l&#8217;occupazione dello Stato della Chiesa aveva immesso sul mercato una quantit\u00e0 enorme di libri religiosi a prezzi vantaggiosi. All&#8217;arrivo di P. Reuss la Biblioteca possedeva circa 1.000 volumi e il numero sal\u00ec a 25.000 nel 1905. Con la fondazione, nel 1949, dell&#8217;Accademia, fin dall&#8217;inizio specializzata in teologia morale, si svilupparono nuove prospettive. Questa scelta decisiva ha determinato la politica delle acquisizioni future, realizzata sistematicamente solo dal &#8217;74 in poi con il mandato di P. Martin Benzerath (1917-2007). Negli anni &#8217;90 viene realizzata dal P. Marian Brudzisz una completa ristrutturazione architettonica e biblioteconomica, che introduce la catalogazione elettronica ed i collegamenti online dei dati bibliografici. Ora la Biblioteca cerca di conseguire i suoi nuovi obiettivi: offrire a insegnanti e studenti una documentazione, la pi\u00f9 completa possibile, per lo studio e l&#8217;approfondimento, per la preparazione di seminari, per l&#8217;elaborazione di licenze, dottorati, tesi, memorie e, infine, per la pubblicazione di libri e articoli.<\/p>\n<p><strong>L&#8217;incremento delle raccolte si sviluppa attualmente in diverse direzioni<\/strong>:<\/p>\n<p style=\"text-align: justify;\">1. Completare il vecchio fondo per continuare l&#8217;opera iniziata da P. Reuss. E\u2019 in atto il suo ampliamento non solo con l&#8217;integrazione di fondi antichi sull&#8217;etica protestante e filosofica, ma anche con la raccolta di libri pubblicati in tutte le altre lingue. Un altro obiettivo consiste nel riunire il maggior numero possibile di edizioni delle opere pi\u00f9 consultate. Oggi l&#8217;acquisizione di opere rare e preziose viene nuovamente facilitata dalla chiusura di tante case religiose, che donano spesso le loro collezioni.<\/p>\n<p style=\"text-align: justify;\">2. Acquisire pubblicazioni recenti nel campo della morale e dell&#8217;etica filosofica. Si cerca, ove possibile, di mettere insieme i testi originali e le loro traduzioni in molte lingue, a partire da quella italiana. Questo impegno si estende anche ai fascicoli, che contano diverse migliaia di unit\u00e0.<\/p>\n<p style=\"text-align: justify;\">3. Documentare le problematicit\u00e0 del mondo contemporaneo, ampliando lo sguardo verso i nuovi orizzonti aperti da teologia, etica, storia, comunicazione, tecnica, scienze, economia, ecologia.<\/p>\n<p style=\"text-align: justify;\">4.\u00a0 Rappresentare una mediazione, che permetta l&#8217;incontro tra pluralismi culturali e l&#8217;universo della produzione editoriale, diventando strumento essenziale per la ricerca, la\u00a0 formazione costante, la creazione di una consapevolezza critica e la produzione di conoscenza, che si traducano in strumenti di sviluppo personale e collettivo.<\/p>\n<p style=\"text-align: justify;\">5. Offrire, attraverso l&#8217;opac Ossegenius, un collegamento permanente al patrimonio bibliografico della Biblioteca.<\/p>\n<p style=\"text-align: justify;\">6. Digitalizzare il materiale pi\u00f9 usato per agevolarne la consultazione e la diffusione.<\/p>\n<p style=\"text-align: justify;\" align=\"left\">L&#8217;impegno del Prof. Ivan Rebernik, di P. Marian Brudzisz e di altri bibliotecari sensibili alla collaborazione ha permesso di creare la rete URBE (Unione Romana Biblioteche Ecclesiastiche), che riunisce Universit\u00e0 e Accademie diverse per specializzazioni e utenza. La Biblioteca ne fa parte dal 1991. Questa partecipazione ha permesso di avviare nel 1994 la catalogazione elettronica prima con il programma Aleph ed attualmente con Olisuite. Ora da tutto il mondo \u00e8 possibile consultare il nostro patrimonio bibliografico, che conta pi\u00f9 di 236.000 titoli di libri e 1.264 di riviste, tra cui circa 267 attive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin dalla fondazione della Casa Generalizia dei Padri Redentoristi nel 1855 esisteva una Biblioteca. Uno dei suoi primi fondi fu[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/pages\/106"}],"collection":[{"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/comments?post=106"}],"version-history":[{"count":8,"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/pages\/106\/revisions"}],"predecessor-version":[{"id":1551,"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/pages\/106\/revisions\/1551"}],"wp:attachment":[{"href":"https:\/\/www.alfonsiana.eu\/biblioteca\/wp-json\/wp\/v2\/media?parent=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}